{"id":3502,"date":"2023-09-09T13:33:53","date_gmt":"2023-09-09T17:33:53","guid":{"rendered":"https:\/\/www.afrokuba.net\/?p=3502"},"modified":"2023-09-09T13:33:57","modified_gmt":"2023-09-09T17:33:57","slug":"camaguey-a-las-puertas-del-olorum-2023","status":"publish","type":"post","link":"https:\/\/www.afrokuba.com\/en\/2023\/09\/09\/camaguey-a-las-puertas-del-olorum-2023\/","title":{"rendered":"CAMAGUEY A LAS PUERTAS DEL OLORUM 2023"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Por:&nbsp; Gleivys Fleites Gonz\u00e1lez y Orestes G. Casanova (Proyecto Etnovisual AFROKUBA)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El viernes 8 de septiembre, coincidiendo con el la festividad de la Virgen de la Caridad del Cobre, Patrona de Cuba, tuvo lugar la conferencia de prensa de la ONCENA edici\u00f3n del Festival OLORUM \u201cIrradiando Ach\u00e9\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El evento se llevar\u00e1 a cabo del 14 al 17 de septiembre en la capital agramontina, organizado, como de costumbre, por el Ballet Folkl\u00f3rico de Camag\u00fcey -bajo la direcci\u00f3n de Reynaldo Echemend\u00eda Estrada- y el Consejo Provincial de las Artes Esc\u00e9nicas del territorio agramontino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cita est\u00e1 dedicada a la maestra Bertha Armi\u00f1\u00e1n Linares y a la figura de la mujer en la danza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El programa del OLORUM 2023 se caracteriza por su diversidad e incluye conferencias, presentaci\u00f3n de audiovisuales, clases magistrales, conversatorios, apertura de exposiciones de artes pl\u00e1sticas y, desde luego, la actuaci\u00f3n de agrupaciones nacionales y extranjeras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre estas figuran, por ejemplo, el Conjunto Folkl\u00f3rico Nacional de Cuba, el Teatro de la Danza del Caribe, el grupo Oy\u00fa Oro, La Chancla (de M\u00e9xico), y el Ballet Folkl\u00f3rico de Camag\u00fcey.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el Festival estar\u00e1n presentes personalidades como los doctores Ismael Albelo y Lilian Chac\u00f3n, los MsC. Marilyn Garbey y Yoilan Maceo, y los Premios Nacionales de Danza, Santiago Alfonso y Johannes Garc\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la clausura se le entregar\u00e1 el Premio OLORUM a la cantante y bailarina santiaguera, la maestra Bertha Armi\u00f1\u00e1n Linares.<\/p>","protected":false},"excerpt":{"rendered":"<p>El viernes 8 de septiembre, coincidiendo con el la festividad de la Virgen de la Caridad del Cobre, Patrona de Cuba, tuvo lugar la conferencia de prensa de la ONCENA edici\u00f3n del Festival OLORUM \u201cIrradiando Ach\u00e9\u201d.<\/p>","protected":false},"author":1,"featured_media":3503,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[117],"tags":[71],"class_list":["post-3502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-festival","tag-arte","post-with-thumbnail","post-with-thumbnail-large"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"El viernes 8 de septiembre, coincidiendo con el la festividad de la Virgen de la Caridad del Cobre, Patrona de Cuba, tuvo lugar la conferencia de prensa de la ONCENA edici\u00f3n del Festival OLORUM \u201cIrradiando Ach\u00e9\u201d.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"AfroKuba\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.afrokuba.com\/en\/2023\/09\/09\/camaguey-a-las-puertas-del-olorum-2023\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"AfroKuba | Proyecto Etnovisual\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"CAMAGUEY A LAS PUERTAS DEL OLORUM 2023 | AfroKuba\" \/>\n\t\t<meta property=\"og:description\" content=\"El viernes 8 de septiembre, coincidiendo con el la festividad de la Virgen de la Caridad del Cobre, Patrona de Cuba, tuvo lugar la conferencia de prensa de la ONCENA edici\u00f3n del Festival OLORUM \u201cIrradiando Ach\u00e9\u201d.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.afrokuba.com\/en\/2023\/09\/09\/camaguey-a-las-puertas-del-olorum-2023\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.afrokuba.com\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-09-at-12.51.04.jpeg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.afrokuba.com\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-09-at-12.51.04.jpeg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t\t<meta property=\"og:image:height\" content=\"995\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-09-09T17:33:53+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-09-09T17:33:57+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/afrokuba\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"CAMAGUEY A LAS PUERTAS DEL OLORUM 2023 | AfroKuba\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El viernes 8 de septiembre, coincidiendo con el la festividad de la Virgen de la Caridad del Cobre, Patrona de Cuba, tuvo lugar la conferencia de prensa de la ONCENA edici\u00f3n del Festival OLORUM \u201cIrradiando Ach\u00e9\u201d.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.afrokuba.com\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-09-at-12.51.04.jpeg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/2023\\\/09\\\/09\\\/camaguey-a-las-puertas-del-olorum-2023\\\/#blogposting\",\"name\":\"CAMAGUEY A LAS PUERTAS DEL OLORUM 2023 | AfroKuba\",\"headline\":\"CAMAGUEY A LAS PUERTAS DEL OLORUM 2023\",\"author\":{\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/author\\\/afrokuba\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.afrokuba.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/WhatsApp-Image-2023-09-09-at-12.51.04.jpeg\",\"width\":720,\"height\":995},\"datePublished\":\"2023-09-09T13:33:53-04:00\",\"dateModified\":\"2023-09-09T13:33:57-04:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/2023\\\/09\\\/09\\\/camaguey-a-las-puertas-del-olorum-2023\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/2023\\\/09\\\/09\\\/camaguey-a-las-puertas-del-olorum-2023\\\/#webpage\"},\"articleSection\":\"Festival, Arte\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/2023\\\/09\\\/09\\\/camaguey-a-las-puertas-del-olorum-2023\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.afrokuba.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/category\\\/festival\\\/#listItem\",\"name\":\"Festival\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/category\\\/festival\\\/#listItem\",\"position\":2,\"name\":\"Festival\",\"item\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/category\\\/festival\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/2023\\\/09\\\/09\\\/camaguey-a-las-puertas-del-olorum-2023\\\/#listItem\",\"name\":\"CAMAGUEY A LAS PUERTAS DEL OLORUM 2023\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/2023\\\/09\\\/09\\\/camaguey-a-las-puertas-del-olorum-2023\\\/#listItem\",\"position\":3,\"name\":\"CAMAGUEY A LAS PUERTAS DEL OLORUM 2023\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/category\\\/festival\\\/#listItem\",\"name\":\"Festival\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/#person\",\"name\":\"AfroKuba\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/2023\\\/09\\\/09\\\/camaguey-a-las-puertas-del-olorum-2023\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/afd997acb9542c3283201cbde65b66699099b658e043adf43bf09f0d1d4778a0?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"AfroKuba\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/author\\\/afrokuba\\\/#author\",\"url\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/author\\\/afrokuba\\\/\",\"name\":\"AfroKuba\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/2023\\\/09\\\/09\\\/camaguey-a-las-puertas-del-olorum-2023\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/afd997acb9542c3283201cbde65b66699099b658e043adf43bf09f0d1d4778a0?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"AfroKuba\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/2023\\\/09\\\/09\\\/camaguey-a-las-puertas-del-olorum-2023\\\/#webpage\",\"url\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/2023\\\/09\\\/09\\\/camaguey-a-las-puertas-del-olorum-2023\\\/\",\"name\":\"CAMAGUEY A LAS PUERTAS DEL OLORUM 2023 | AfroKuba\",\"description\":\"El viernes 8 de septiembre, coincidiendo con el la festividad de la Virgen de la Caridad del Cobre, Patrona de Cuba, tuvo lugar la conferencia de prensa de la ONCENA edici\\u00f3n del Festival OLORUM \\u201cIrradiando Ach\\u00e9\\u201d.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/2023\\\/09\\\/09\\\/camaguey-a-las-puertas-del-olorum-2023\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/author\\\/afrokuba\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/author\\\/afrokuba\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.afrokuba.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/WhatsApp-Image-2023-09-09-at-12.51.04.jpeg\",\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/2023\\\/09\\\/09\\\/camaguey-a-las-puertas-del-olorum-2023\\\/#mainImage\",\"width\":720,\"height\":995},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/2023\\\/09\\\/09\\\/camaguey-a-las-puertas-del-olorum-2023\\\/#mainImage\"},\"datePublished\":\"2023-09-09T13:33:53-04:00\",\"dateModified\":\"2023-09-09T13:33:57-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/\",\"name\":\"AfroKuba\",\"description\":\"Proyecto Etnovisual\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.afrokuba.com\\\/en\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"CAMAGUEY A LAS PUERTAS DEL OLORUM 2023 | AfroKuba","description":"El viernes 8 de septiembre, coincidiendo con el la festividad de la Virgen de la Caridad del Cobre, Patrona de Cuba, tuvo lugar la conferencia de prensa de la ONCENA edici\u00f3n del Festival OLORUM \u201cIrradiando Ach\u00e9\u201d.","canonical_url":"https:\/\/www.afrokuba.com\/en\/2023\/09\/09\/camaguey-a-las-puertas-del-olorum-2023\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.afrokuba.com\/en\/2023\/09\/09\/camaguey-a-las-puertas-del-olorum-2023\/#blogposting","name":"CAMAGUEY A LAS PUERTAS DEL OLORUM 2023 | AfroKuba","headline":"CAMAGUEY A LAS PUERTAS DEL OLORUM 2023","author":{"@id":"https:\/\/www.afrokuba.com\/en\/author\/afrokuba\/#author"},"publisher":{"@id":"https:\/\/www.afrokuba.com\/en\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.afrokuba.com\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-09-at-12.51.04.jpeg","width":720,"height":995},"datePublished":"2023-09-09T13:33:53-04:00","dateModified":"2023-09-09T13:33:57-04:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/www.afrokuba.com\/en\/2023\/09\/09\/camaguey-a-las-puertas-del-olorum-2023\/#webpage"},"isPartOf":{"@id":"https:\/\/www.afrokuba.com\/en\/2023\/09\/09\/camaguey-a-las-puertas-del-olorum-2023\/#webpage"},"articleSection":"Festival, Arte"},{"@type":"BreadcrumbList","@id":"https:\/\/www.afrokuba.com\/en\/2023\/09\/09\/camaguey-a-las-puertas-del-olorum-2023\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.afrokuba.com\/en#listItem","position":1,"name":"Inicio","item":"https:\/\/www.afrokuba.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/www.afrokuba.com\/en\/category\/festival\/#listItem","name":"Festival"}},{"@type":"ListItem","@id":"https:\/\/www.afrokuba.com\/en\/category\/festival\/#listItem","position":2,"name":"Festival","item":"https:\/\/www.afrokuba.com\/en\/category\/festival\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.afrokuba.com\/en\/2023\/09\/09\/camaguey-a-las-puertas-del-olorum-2023\/#listItem","name":"CAMAGUEY A LAS PUERTAS DEL OLORUM 2023"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.afrokuba.com\/en#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/www.afrokuba.com\/en\/2023\/09\/09\/camaguey-a-las-puertas-del-olorum-2023\/#listItem","position":3,"name":"CAMAGUEY A LAS PUERTAS DEL OLORUM 2023","previousItem":{"@type":"ListItem","@id":"https:\/\/www.afrokuba.com\/en\/category\/festival\/#listItem","name":"Festival"}}]},{"@type":"Person","@id":"https:\/\/www.afrokuba.com\/en\/#person","name":"AfroKuba","image":{"@type":"ImageObject","@id":"https:\/\/www.afrokuba.com\/en\/2023\/09\/09\/camaguey-a-las-puertas-del-olorum-2023\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/afd997acb9542c3283201cbde65b66699099b658e043adf43bf09f0d1d4778a0?s=96&d=mm&r=g","width":96,"height":96,"caption":"AfroKuba"}},{"@type":"Person","@id":"https:\/\/www.afrokuba.com\/en\/author\/afrokuba\/#author","url":"https:\/\/www.afrokuba.com\/en\/author\/afrokuba\/","name":"AfroKuba","image":{"@type":"ImageObject","@id":"https:\/\/www.afrokuba.com\/en\/2023\/09\/09\/camaguey-a-las-puertas-del-olorum-2023\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/afd997acb9542c3283201cbde65b66699099b658e043adf43bf09f0d1d4778a0?s=96&d=mm&r=g","width":96,"height":96,"caption":"AfroKuba"}},{"@type":"WebPage","@id":"https:\/\/www.afrokuba.com\/en\/2023\/09\/09\/camaguey-a-las-puertas-del-olorum-2023\/#webpage","url":"https:\/\/www.afrokuba.com\/en\/2023\/09\/09\/camaguey-a-las-puertas-del-olorum-2023\/","name":"CAMAGUEY A LAS PUERTAS DEL OLORUM 2023 | AfroKuba","description":"El viernes 8 de septiembre, coincidiendo con el la festividad de la Virgen de la Caridad del Cobre, Patrona de Cuba, tuvo lugar la conferencia de prensa de la ONCENA edici\u00f3n del Festival OLORUM \u201cIrradiando Ach\u00e9\u201d.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/www.afrokuba.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.afrokuba.com\/en\/2023\/09\/09\/camaguey-a-las-puertas-del-olorum-2023\/#breadcrumblist"},"author":{"@id":"https:\/\/www.afrokuba.com\/en\/author\/afrokuba\/#author"},"creator":{"@id":"https:\/\/www.afrokuba.com\/en\/author\/afrokuba\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.afrokuba.com\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-09-at-12.51.04.jpeg","@id":"https:\/\/www.afrokuba.com\/en\/2023\/09\/09\/camaguey-a-las-puertas-del-olorum-2023\/#mainImage","width":720,"height":995},"primaryImageOfPage":{"@id":"https:\/\/www.afrokuba.com\/en\/2023\/09\/09\/camaguey-a-las-puertas-del-olorum-2023\/#mainImage"},"datePublished":"2023-09-09T13:33:53-04:00","dateModified":"2023-09-09T13:33:57-04:00"},{"@type":"WebSite","@id":"https:\/\/www.afrokuba.com\/en\/#website","url":"https:\/\/www.afrokuba.com\/en\/","name":"AfroKuba","description":"Proyecto Etnovisual","inLanguage":"en-US","publisher":{"@id":"https:\/\/www.afrokuba.com\/en\/#person"}}]},"og:locale":"en_US","og:site_name":"AfroKuba | Proyecto Etnovisual","og:type":"article","og:title":"CAMAGUEY A LAS PUERTAS DEL OLORUM 2023 | AfroKuba","og:description":"El viernes 8 de septiembre, coincidiendo con el la festividad de la Virgen de la Caridad del Cobre, Patrona de Cuba, tuvo lugar la conferencia de prensa de la ONCENA edici\u00f3n del Festival OLORUM \u201cIrradiando Ach\u00e9\u201d.","og:url":"https:\/\/www.afrokuba.com\/en\/2023\/09\/09\/camaguey-a-las-puertas-del-olorum-2023\/","og:image":"https:\/\/www.afrokuba.com\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-09-at-12.51.04.jpeg","og:image:secure_url":"https:\/\/www.afrokuba.com\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-09-at-12.51.04.jpeg","og:image:width":720,"og:image:height":995,"article:published_time":"2023-09-09T17:33:53+00:00","article:modified_time":"2023-09-09T17:33:57+00:00","article:publisher":"https:\/\/www.facebook.com\/afrokuba\/","twitter:card":"summary","twitter:title":"CAMAGUEY A LAS PUERTAS DEL OLORUM 2023 | AfroKuba","twitter:description":"El viernes 8 de septiembre, coincidiendo con el la festividad de la Virgen de la Caridad del Cobre, Patrona de Cuba, tuvo lugar la conferencia de prensa de la ONCENA edici\u00f3n del Festival OLORUM \u201cIrradiando Ach\u00e9\u201d.","twitter:image":"https:\/\/www.afrokuba.com\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-09-at-12.51.04.jpeg"},"aioseo_meta_data":{"post_id":"3502","title":null,"description":"El viernes 8 de septiembre, coincidiendo con el la festividad de la Virgen de la Caridad del Cobre, Patrona de Cuba, tuvo lugar la conferencia de prensa de la ONCENA edici\u00f3n del Festival OLORUM \u201cIrradiando Ach\u00e9\u201d.","keywords":[],"keyphrases":{"focus":{"keyphrase":"OLORUM 2023","score":50,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":3,"maxScore":9,"error":1},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":3,"maxScore":9,"error":1},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":[],"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-09-09 17:33:57","updated":"2025-06-04 04:29:10","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.afrokuba.com\/en\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.afrokuba.com\/en\/category\/festival\/\" title=\"Festival\">Festival<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCAMAGUEY A LAS PUERTAS DEL OLORUM 2023\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/www.afrokuba.com\/en"},{"label":"Festival","link":"https:\/\/www.afrokuba.com\/en\/category\/festival\/"},{"label":"CAMAGUEY A LAS PUERTAS DEL OLORUM 2023","link":"https:\/\/www.afrokuba.com\/en\/2023\/09\/09\/camaguey-a-las-puertas-del-olorum-2023\/"}],"jetpack_featured_media_url":"https:\/\/www.afrokuba.com\/wp-content\/uploads\/2023\/09\/WhatsApp-Image-2023-09-09-at-12.51.04.jpeg","_links":{"self":[{"href":"https:\/\/www.afrokuba.com\/en\/wp-json\/wp\/v2\/posts\/3502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.afrokuba.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.afrokuba.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.afrokuba.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.afrokuba.com\/en\/wp-json\/wp\/v2\/comments?post=3502"}],"version-history":[{"count":0,"href":"https:\/\/www.afrokuba.com\/en\/wp-json\/wp\/v2\/posts\/3502\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.afrokuba.com\/en\/wp-json\/wp\/v2\/media\/3503"}],"wp:attachment":[{"href":"https:\/\/www.afrokuba.com\/en\/wp-json\/wp\/v2\/media?parent=3502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.afrokuba.com\/en\/wp-json\/wp\/v2\/categories?post=3502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.afrokuba.com\/en\/wp-json\/wp\/v2\/tags?post=3502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}